{"id":368,"date":"2006-12-11T19:51:21","date_gmt":"2006-12-11T18:51:21","guid":{"rendered":"http:\/\/kmim.wm.pwr.edu.pl\/immt\/2006\/12\/11\/prezydent-rp-wreczyl-nominacje-profesorskie\/"},"modified":"2014-11-07T21:53:52","modified_gmt":"2014-11-07T20:53:52","slug":"prezydent-rp-wreczyl-nominacje-profesorskie","status":"publish","type":"post","link":"https:\/\/kmim.wm.pwr.edu.pl\/immt\/2006\/12\/11\/prezydent-rp-wreczyl-nominacje-profesorskie\/","title":{"rendered":"Prezydent RP wr\u0119czy\u0142 nominacje profesorskie"},"content":{"rendered":"<p>30 listopada 2006 r. Prezydent Rzeczypospolitej Polskiej Lech Kaczy\u0144ski wr\u0119czy\u0142 w Pa\u0142acu Prezydenckim nominacje profesorskie nauczycielom akademickim oraz pracownikom nauki i sztuki.<\/p>\n<p>W dziedzinie\u00a0 Nauki Techniczne nominacj\u0119 odebra\u0142 dr hab. in\u017c. <span style=\"font-weight: bold;\">Maciej Wac\u0142aw Kulisiewicz<\/span>, kierownik Zak\u0142adu Mechaniki O\u015brodk\u00f3w dyskretnych.<\/p>\n<p>Na naszych stronach znajduje si\u0119 kr\u00f3tka fotorelacja z tej uroczysto\u015bci.<\/p>\n<p>Serdecznie gratulujemy!<\/p>\n<p>Pe\u0142na lista nominowanych znajduje si\u0119 na stronach <a href=\"http:\/\/www.prezydent.pl\/x.node?id=1011848&amp;eventId=8027336\" target=\"_blank\">Prezydenta Rzeczypospolitej Polskiej<\/a>.<\/p>\n<div id='gallery-1' class='gallery galleryid-368 gallery-columns-3 gallery-size-thumbnail'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/kmim.wm.pwr.edu.pl\/immt\/2006\/12\/11\/prezydent-rp-wreczyl-nominacje-profesorskie\/slide_dsc00535\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-content\/uploads\/sites\/58\/2006\/12\/slide_DSC00535-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/kmim.wm.pwr.edu.pl\/immt\/2006\/12\/11\/prezydent-rp-wreczyl-nominacje-profesorskie\/slide_dsc00549\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-content\/uploads\/sites\/58\/2006\/12\/slide_DSC00549-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/kmim.wm.pwr.edu.pl\/immt\/2006\/12\/11\/prezydent-rp-wreczyl-nominacje-profesorskie\/slide_dsc00574\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-content\/uploads\/sites\/58\/2006\/12\/slide_DSC00574-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/kmim.wm.pwr.edu.pl\/immt\/2006\/12\/11\/prezydent-rp-wreczyl-nominacje-profesorskie\/slide_dsc00571\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-content\/uploads\/sites\/58\/2006\/12\/slide_DSC00571-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/kmim.wm.pwr.edu.pl\/immt\/2006\/12\/11\/prezydent-rp-wreczyl-nominacje-profesorskie\/slide_dsc00576\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-content\/uploads\/sites\/58\/2006\/12\/slide_DSC00576-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" srcset=\"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-content\/uploads\/sites\/58\/2006\/12\/slide_DSC00576-150x150.jpg 150w, https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-content\/uploads\/sites\/58\/2006\/12\/slide_DSC00576-369x372.jpg 369w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/kmim.wm.pwr.edu.pl\/immt\/2006\/12\/11\/prezydent-rp-wreczyl-nominacje-profesorskie\/slide_dsc00594\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-content\/uploads\/sites\/58\/2006\/12\/slide_DSC00594-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/kmim.wm.pwr.edu.pl\/immt\/2006\/12\/11\/prezydent-rp-wreczyl-nominacje-profesorskie\/slide_dsc00554\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-content\/uploads\/sites\/58\/2006\/12\/slide_DSC00554-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/kmim.wm.pwr.edu.pl\/immt\/2006\/12\/11\/prezydent-rp-wreczyl-nominacje-profesorskie\/slide_dsc00553\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-content\/uploads\/sites\/58\/2006\/12\/slide_DSC00553-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='https:\/\/kmim.wm.pwr.edu.pl\/immt\/2006\/12\/11\/prezydent-rp-wreczyl-nominacje-profesorskie\/slide_dsc00515\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-content\/uploads\/sites\/58\/2006\/12\/slide_DSC00515-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/kmim.wm.pwr.edu.pl\/immt\/2006\/12\/11\/prezydent-rp-wreczyl-nominacje-profesorskie\/slide_dsc00578\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-content\/uploads\/sites\/58\/2006\/12\/slide_DSC00578-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/kmim.wm.pwr.edu.pl\/immt\/2006\/12\/11\/prezydent-rp-wreczyl-nominacje-profesorskie\/slide_dsc00552\/'><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-content\/uploads\/sites\/58\/2006\/12\/slide_DSC00552-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail\" alt=\"\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>30 listopada 2006 r. Prezydent Rzeczypospolitej Polskiej Lech Kaczy\u0144ski wr\u0119czy\u0142 w Pa\u0142acu Prezydenckim nominacje profesorskie nauczycielom akademickim oraz pracownikom nauki i sztuki. W dziedzinie\u00a0 Nauki Techniczne nominacj\u0119 odebra\u0142 dr hab. in\u017c. Maciej Wac\u0142aw Kulisiewicz, kierownik Zak\u0142adu Mechaniki O\u015brodk\u00f3w dyskretnych. Na naszych stronach znajduje si\u0119 kr\u00f3tka fotorelacja z tej uroczysto\u015bci. Serdecznie gratulujemy! Pe\u0142na lista nominowanych znajduje &hellip; <a href=\"https:\/\/kmim.wm.pwr.edu.pl\/immt\/2006\/12\/11\/prezydent-rp-wreczyl-nominacje-profesorskie\/\" class=\"more-link\">Czytaj dalej <span class=\"screen-reader-text\">Prezydent RP wr\u0119czy\u0142 nominacje profesorskie<\/span> <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-368","post","type-post","status-publish","format-standard","hentry","category-instytut"],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:28:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-json\/wp\/v2\/posts\/368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-json\/wp\/v2\/comments?post=368"}],"version-history":[{"count":2,"href":"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-json\/wp\/v2\/posts\/368\/revisions"}],"predecessor-version":[{"id":1992,"href":"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-json\/wp\/v2\/posts\/368\/revisions\/1992"}],"wp:attachment":[{"href":"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-json\/wp\/v2\/media?parent=368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-json\/wp\/v2\/categories?post=368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kmim.wm.pwr.edu.pl\/immt\/wp-json\/wp\/v2\/tags?post=368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}